{"id":99759,"date":"2022-03-17T08:40:04","date_gmt":"2022-03-17T07:40:04","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=99759"},"modified":"2025-12-18T16:50:37","modified_gmt":"2025-12-18T15:50:37","slug":"carbaryl-copia-159","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/rm-en\/532-24-1-tropinone-rm\/","title":{"rendered":"Tropinone"},"content":{"rendered":"<table class=\"table-product-codes\">\n<tbody class=\"tbody-table-product-codes\">\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CAS Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">532-24-1<\/td>\n<td class=\"td-table-product-codes\"><strong>Molecular Weight (g\/mol):<\/strong><\/td>\n<td class=\"td-table-product-codes\">139,2<\/td>\n<td class=\"td-table-product-codes\"><strong>Beilstein:<\/strong><\/td>\n<td class=\"td-table-product-codes\">2329<\/td>\n<\/tr>\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CE Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">208-530-6<\/td>\n<td class=\"td-table-product-codes\"><strong>MDL Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">MFCD00005549<\/td>\n<td class=\"td-table-product-codes\"><strong>ID PubChem:<\/strong><\/td>\n<td class=\"td-table-product-codes\"><a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/79038\" target=\"_blank\" rel=\"noopener\">79038<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"table-product\">\n<tbody class=\"tbody-table-product\">\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>IUPAC Name<\/strong><\/td>\n<td class=\"td-table-product\">8-methyl-8-azabicyclo[3.2.1]octan-3-one<\/td>\n<\/tr>\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>Linear Formula<\/strong><\/td>\n<td class=\"td-table-product\"><span id=\"chem-formula\">C8H13NO<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><strong>CAS:<\/strong> 532-24-1<\/p>\n","protected":false},"featured_media":90474,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[178],"product_tag":[],"class_list":["post-99759","product","type-product","status-publish","has-post-thumbnail","product_cat-rm","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/99759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/90474"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=99759"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=99759"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=99759"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=99759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}