{"id":95339,"date":"2022-03-14T09:39:22","date_gmt":"2022-03-14T08:39:23","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=95339"},"modified":"2022-03-14T09:44:43","modified_gmt":"2022-03-14T08:44:43","slug":"acrinathrin-copia-109","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/rm-en\/82-28-0-disperse-orange-11-rm\/","title":{"rendered":"Disperse Orange 11"},"content":{"rendered":"<table class='table-product-codes'>\n<tbody class='tbody-table-product-codes'>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CAS Number:<\/strong><\/td>\n<td class='td-table-product-codes'>82-28-0<\/td>\n<td class='td-table-product-codes'><strong>MW (g\/mol):<\/strong><\/td>\n<td class='td-table-product-codes'>237,25<\/td>\n<td class='td-table-product-codes'><strong>Beilstein:<\/strong><\/td>\n<td class='td-table-product-codes'>n.a.<\/td>\n<\/tr>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CE Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n 201-408-3<\/td>\n<td class='td-table-product-codes'><strong>MDL Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n MFCD00001220<\/td>\n<td class='td-table-product-codes'><strong>ID PubChem:<\/strong><\/td>\n<td class='td-table-product-codes'><a href='https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/6702' target='_blank' rel=\"noopener\">6702<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class='table-product'>\n<tbody class='tbody-table-product'>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>IUPAC Name<\/strong><\/td>\n<td class='td-table-product'>1-amino-2-methylanthracene-9,10-dione<\/p>\n<\/td>\n<\/tr>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>Linear Formula<\/strong><\/td>\n<td class='td-table-product'><span id='chem-formula'>C15H11NO2<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>CAS Number: 82-28-0 MW (g\/mol): 237,25 Beilstein: n.a. CE Number: 201-408-3 MDL Number: MFCD00001220 ID PubChem: 6702 IUPAC Name 1-amino-2-methylanthracene-9,10-dione Linear Formula C15H11NO2<\/p>\n","protected":false},"featured_media":89972,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[184],"product_tag":[],"class_list":["post-95339","product","type-product","status-publish","has-post-thumbnail","product_cat-rm-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/95339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/89972"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=95339"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=95339"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=95339"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=95339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}