{"id":261677,"date":"2022-06-14T12:18:42","date_gmt":"2022-06-14T10:18:42","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=261677"},"modified":"2025-12-17T13:05:03","modified_gmt":"2025-12-17T12:05:03","slug":"carbaryl-solution-copia-468-36","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/analytical-standard-solution-en\/76-87-9-fentin-hydroxide-solution-analytical-standard\/","title":{"rendered":"Fentin-Hydroxide solution"},"content":{"rendered":"<table class=\"table-product-codes\">\n<tbody class=\"tbody-table-product-codes\">\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CAS Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">76-87-9<\/td>\n<td class=\"td-table-product-codes\"><strong>Molecular Weight (g\/mol):<\/strong><\/td>\n<td class=\"td-table-product-codes\">368<\/td>\n<td class=\"td-table-product-codes\"><strong>Beilstein:<\/strong><\/td>\n<td class=\"td-table-product-codes\">4139186<\/td>\n<\/tr>\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CE Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">200-990-6<\/td>\n<td class=\"td-table-product-codes\"><strong>MDL Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">MFCD00013928<\/td>\n<td class=\"td-table-product-codes\"><strong>ID PubChem:<\/strong><\/td>\n<td class=\"td-table-product-codes\"><a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/6327657\" target=\"_blank\" rel=\"noopener\">6327657<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"table-product\">\n<tbody class=\"tbody-table-product\">\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>IUPAC Name<\/strong><\/td>\n<td class=\"td-table-product\">n\/a<\/td>\n<\/tr>\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>Linear Formula<\/strong><\/td>\n<td class=\"td-table-product\"><span id=\"chem-formula\">C18H17OSn<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><b>CAS: <\/b>76-87-9<\/p>\n","protected":false},"featured_media":3366,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[182],"product_tag":[],"class_list":["post-261677","product","type-product","status-publish","has-post-thumbnail","product_cat-analytical-standard-solution-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/261677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/3366"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=261677"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=261677"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=261677"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=261677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}