{"id":259391,"date":"2022-06-13T08:45:33","date_gmt":"2022-06-13T06:45:37","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=259391"},"modified":"2022-06-13T08:50:52","modified_gmt":"2022-06-13T06:50:52","slug":"triclopyr-methyl-solution-copia-128","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/rm-solution-en\/79540-50-4-etobenzanid-solution-rm\/","title":{"rendered":"Etobenzanid solution"},"content":{"rendered":"<table class='table-product-codes'>\n<tbody class='tbody-table-product-codes'>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CAS Number:<\/strong><\/td>\n<td class='td-table-product-codes'>79540-50-4<\/td>\n<td class='td-table-product-codes'><strong>MW (g\/mol):<\/strong><\/td>\n<td class='td-table-product-codes'>340.20<\/td>\n<td class='td-table-product-codes'><strong>Beilstein:<\/strong><\/td>\n<td class='td-table-product-codes'>n.a.<\/td>\n<\/tr>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CE Number:<\/strong><\/td>\n<td class='td-table-product-codes'>n.a.<\/td>\n<td class='td-table-product-codes'><strong>MDL Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n MFCD01631156<\/td>\n<td class='td-table-product-codes'><strong>ID PubChem:<\/strong><\/td>\n<td class='td-table-product-codes'><a href='https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/12771065' target='_blank' rel=\"noopener\">12771065<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class='table-product'>\n<tbody class='tbody-table-product'>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>IUPAC Name<\/strong><\/td>\n<td class='td-table-product'>N-(2,3-dichlorophenyl)-4-(ethoxymethoxy)benzamide<\/td>\n<\/tr>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>Linear Formula<\/strong><\/td>\n<td class='td-table-product'><span id='chem-formula'>C16H15Cl2NO3<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><b>CAS: <\/b>79540-50-4<\/p>\n","protected":false},"featured_media":86733,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[186],"product_tag":[],"class_list":["post-259391","product","type-product","status-publish","has-post-thumbnail","product_cat-rm-solution","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/259391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/86733"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=259391"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=259391"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=259391"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=259391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}