{"id":257164,"date":"2022-06-10T16:44:23","date_gmt":"2022-06-10T14:44:23","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=257164"},"modified":"2025-12-29T15:43:09","modified_gmt":"2025-12-29T14:43:09","slug":"hydroxy-flubendazole-solution-copia-450","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/rm-solution-en\/8003-34-7-pyrethrins-solution-rm\/","title":{"rendered":"Pyrethrins solution"},"content":{"rendered":"<table class=\"table-product-codes\">\n<tbody class=\"tbody-table-product-codes\">\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CAS Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">8003-34-7<\/td>\n<td class=\"td-table-product-codes\"><strong>Molecular Weight (g\/mol):<\/strong><\/td>\n<td class=\"td-table-product-codes\">700.9<\/td>\n<td class=\"td-table-product-codes\"><strong>Beilstein:<\/strong><\/td>\n<td class=\"td-table-product-codes\">n.a.<\/td>\n<\/tr>\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CE Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">232-319-8<\/td>\n<td class=\"td-table-product-codes\"><strong>MDL Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">MFCD00078611<\/td>\n<td class=\"td-table-product-codes\"><strong>ID PubChem:<\/strong><\/td>\n<td class=\"td-table-product-codes\"><a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/71310221\" target=\"_blank\" rel=\"noopener\">71310221<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"table-product\">\n<tbody class=\"tbody-table-product\">\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>IUPAC Name<\/strong><\/td>\n<td class=\"td-table-product\">[(1S)-2-methyl-4-oxo-3-[(2E)-penta-2,4-dienyl]cyclopent-2-en-1-yl] (1R)-2,2-dimethyl-3-(2-methylprop-1-enyl)cyclopropane-1-carboxylate;[2-methyl-4-oxo-3-[(2E)-penta-2,4-dienyl]cyclopent-2-en-1-yl] (1R)-3-[(E)-3-methoxy-2-methyl-3-oxoprop-1-enyl]-2,2-dimethylcyclopropane-1-carboxylate<\/td>\n<\/tr>\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>Linear Formula<\/strong><\/td>\n<td class=\"td-table-product\"><span id=\"chem-formula\">C43H56O8<br \/>\n<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><b>CAS: <\/b>8003-34-7<\/p>\n","protected":false},"featured_media":85437,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[187],"product_tag":[],"class_list":["post-257164","product","type-product","status-publish","has-post-thumbnail","product_cat-rm-solution-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/257164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/85437"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=257164"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=257164"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=257164"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=257164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}