{"id":252847,"date":"2022-06-09T00:06:11","date_gmt":"2022-06-08T22:06:11","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=252847"},"modified":"2026-01-07T14:26:56","modified_gmt":"2026-01-07T13:26:56","slug":"disulfiram-solution-copia-22","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/rm-solution-en\/153197-14-9-oxaziclomefone-solution-rm\/","title":{"rendered":"Oxaziclomefone solution"},"content":{"rendered":"<table class=\"table-product-codes\">\n<tbody class=\"tbody-table-product-codes\">\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CAS Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">153197-14-9<\/td>\n<td class=\"td-table-product-codes\"><strong>Molecular Weight (g\/mol):<\/strong><\/td>\n<td class=\"td-table-product-codes\">376.27<\/td>\n<td class=\"td-table-product-codes\"><strong>Beilstein:<\/strong><\/td>\n<td class=\"td-table-product-codes\">n.a.<\/td>\n<\/tr>\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CE Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">n.a.<\/td>\n<td class=\"td-table-product-codes\"><strong>MDL Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">MFCD04972565<\/td>\n<td class=\"td-table-product-codes\"><strong>ID PubChem:<\/strong><\/td>\n<td class=\"td-table-product-codes\"><a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/15604135\" target=\"_blank\" rel=\"noopener\">15604135<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"table-product\">\n<tbody class=\"tbody-table-product\">\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>IUPAC Name<\/strong><\/td>\n<td class=\"td-table-product\">3-[2-(3,5-dichlorophenyl)propan-2-yl]-6-methyl-5-phenyl-2H-1,3-oxazin-4-one<\/td>\n<\/tr>\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>Linear Formula<\/strong><\/td>\n<td class=\"td-table-product\"><span id=\"chem-formula\">C20H19Cl2NO2<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><b>CAS: <\/b>153197-14-9<\/p>\n","protected":false},"featured_media":2988,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[187],"product_tag":[],"class_list":["post-252847","product","type-product","status-publish","has-post-thumbnail","product_cat-rm-solution-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/252847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/2988"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=252847"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=252847"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=252847"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=252847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}