{"id":234021,"date":"2022-06-02T07:13:55","date_gmt":"2022-06-02T05:13:59","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=234021"},"modified":"2022-06-02T07:22:33","modified_gmt":"2022-06-02T05:22:33","slug":"roxarsone-solution-copia-124","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/rm-solution-en\/123-75-1-pyrrolidine-solution-rm\/","title":{"rendered":"Pyrrolidine solution"},"content":{"rendered":"<table class='table-product-codes'>\n<tbody class='tbody-table-product-codes'>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CAS Number:<\/strong><\/td>\n<td class='td-table-product-codes'>123-75-1<\/td>\n<td class='td-table-product-codes'><strong>MW (g\/mol):<\/strong><\/td>\n<td class='td-table-product-codes'>71.12<\/td>\n<td class='td-table-product-codes'><strong>Beilstein:<\/strong><\/td>\n<td class='td-table-product-codes'>102395<\/td>\n<\/tr>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CE Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n 204-648-7<\/td>\n<td class='td-table-product-codes'><strong>MDL Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n MFCD00005249<\/td>\n<td class='td-table-product-codes'><strong>ID PubChem:<\/strong><\/td>\n<td class='td-table-product-codes'><a href='https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/31268' target='_blank' rel=\"noopener\">31268<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class='table-product'>\n<tbody class='tbody-table-product'>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>IUPAC Name<\/strong><\/td>\n<td class='td-table-product'>pyrrolidine<\/td>\n<\/tr>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>Linear Formula<\/strong><\/td>\n<td class='td-table-product'><span id='chem-formula'>C4H9N<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><b>CAS: <\/b>123-75-1<\/p>\n","protected":false},"featured_media":83929,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[187],"product_tag":[],"class_list":["post-234021","product","type-product","status-publish","has-post-thumbnail","product_cat-rm-solution-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/234021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/83929"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=234021"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=234021"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=234021"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=234021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}