{"id":192210,"date":"2022-05-10T17:14:45","date_gmt":"2022-05-10T15:14:59","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=192210"},"modified":"2022-05-10T17:25:28","modified_gmt":"2022-05-10T15:25:28","slug":"boscalid-solution-copia-324","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/crm-solution-en\/40596-69-8-methoprene-solution-crm\/","title":{"rendered":"Methoprene solution"},"content":{"rendered":"<table class='table-product-codes'>\n<tbody class='tbody-table-product-codes'>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CAS Number:<\/strong><\/td>\n<td class='td-table-product-codes'>40596-69-8<\/td>\n<td class='td-table-product-codes'><strong>MW (g\/mol):<\/strong><\/td>\n<td class='td-table-product-codes'>310.47<\/td>\n<td class='td-table-product-codes'><strong>Beilstein:<\/strong><\/td>\n<td class='td-table-product-codes'>1913191<\/td>\n<\/tr>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CE Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n 254-993-2<\/td>\n<td class='td-table-product-codes'><strong>MDL Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n MFCD00072475<\/td>\n<td class='td-table-product-codes'><strong>ID PubChem:<\/strong><\/td>\n<td class='td-table-product-codes'><a href='https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/5366546' target='_blank' rel=\"noopener\">5366546<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class='table-product'>\n<tbody class='tbody-table-product'>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>IUPAC Name<\/strong><\/td>\n<td class='td-table-product'>propan-2-yl (2E,4E)-11-methoxy-3,7,11-trimethyldodeca-2,4-dienoate<\/td>\n<\/tr>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>Linear Formula<\/strong><\/td>\n<td class='td-table-product'><span id='chem-formula'>C19H34O3<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><b>CAS: <\/b>40596-69-8<\/p>\n","protected":false},"featured_media":86149,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[180],"product_tag":[],"class_list":["post-192210","product","type-product","status-publish","has-post-thumbnail","product_cat-crm-solution-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/192210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/86149"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=192210"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=192210"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=192210"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=192210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}