{"id":130231,"date":"2022-04-01T10:22:03","date_gmt":"2022-04-01T08:22:03","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=130231"},"modified":"2025-12-23T14:52:11","modified_gmt":"2025-12-23T13:52:11","slug":"chloroethanol-2-d4-copia","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/ilis-en\/ilis-rm-en\/1718-51-0-terphenyl-p-d14-rm\/","title":{"rendered":"Terphenyl, p-D14"},"content":{"rendered":"<table class=\"table-product-codes\">\n<tbody class=\"tbody-table-product-codes\">\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CAS Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">1718-51-0<\/td>\n<td class=\"td-table-product-codes\"><strong>Molecular Weight (g\/mol):<\/strong><\/td>\n<td class=\"td-table-product-codes\">244.39<\/td>\n<td class=\"td-table-product-codes\"><strong>Beilstein:<\/strong><\/td>\n<td class=\"td-table-product-codes\">n.a.<\/td>\n<\/tr>\n<tr class=\"tr-table-product-codes\">\n<td class=\"td-table-product-codes\"><strong>CE Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">n.a.<\/td>\n<td class=\"td-table-product-codes\"><strong>MDL Number:<\/strong><\/td>\n<td class=\"td-table-product-codes\">MFCD00084184<\/td>\n<td class=\"td-table-product-codes\"><strong>ID PubChem:<\/strong><\/td>\n<td class=\"td-table-product-codes\"><a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/123128\" target=\"_blank\" rel=\"noopener\">123128<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"table-product\">\n<tbody class=\"tbody-table-product\">\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>IUPAC Name<\/strong><\/td>\n<td class=\"td-table-product\">1,2,3,4,5-pentadeuterio-6-[2,3,5,6-tetradeuterio-4-(2,3,4,5,6-pentadeuteriophenyl)phenyl]benzene<\/td>\n<\/tr>\n<tr class=\"tr-table-product\">\n<td class=\"td-table-product\"><strong>Linear Formula<\/strong><\/td>\n<td class=\"td-table-product\"><span id=\"chem-formula\">C18D14<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><strong>CAS:<\/strong> 1718-51-0<\/p>\n","protected":false},"featured_media":84833,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[204,184],"product_tag":[],"class_list":["post-130231","product","type-product","status-publish","has-post-thumbnail","product_cat-ilis-rm-en","product_cat-rm-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/130231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/84833"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=130231"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=130231"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=130231"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=130231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}