{"id":101759,"date":"2022-03-17T15:23:31","date_gmt":"2022-03-17T14:23:32","guid":{"rendered":"https:\/\/www.crmlabstandard.com\/?post_type=product&#038;p=101759"},"modified":"2022-03-17T15:26:58","modified_gmt":"2022-03-17T14:26:58","slug":"carbaryl-copia-176","status":"publish","type":"product","link":"https:\/\/www.crmlabstandard.com\/en\/shop\/labstandard\/single-component\/analytical-standard-en\/3296-90-0-22-bisbromomethyl-13-propanediol-analytical-standard\/","title":{"rendered":"2,2-Bis(bromomethyl)-1,3-propanediol"},"content":{"rendered":"<table class='table-product-codes'>\n<tbody class='tbody-table-product-codes'>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CAS Number:<\/strong><\/td>\n<td class='td-table-product-codes'>3296-90-0<\/td>\n<td class='td-table-product-codes'><strong>MW (g\/mol):<\/strong><\/td>\n<td class='td-table-product-codes'>261,94<\/td>\n<td class='td-table-product-codes'><strong>Beilstein:<\/strong><\/td>\n<td class='td-table-product-codes'>n.a.<\/td>\n<\/tr>\n<tr class='tr-table-product-codes'>\n<td class='td-table-product-codes'><strong>CE Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n 221-967-7<\/td>\n<td class='td-table-product-codes'><strong>MDL Number:<\/strong><\/td>\n<td class='td-table-product-codes'>\n MFCD00004688<\/td>\n<td class='td-table-product-codes'><strong>ID PubChem:<\/strong><\/td>\n<td class='td-table-product-codes'><a href='https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/18692' target='_blank' rel=\"noopener\">18692<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class='table-product'>\n<tbody class='tbody-table-product'>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>IUPAC Name<\/strong><\/td>\n<td class='td-table-product'>2,2-bis(bromomethyl)propane-1,3-diol<\/p>\n<\/td>\n<\/tr>\n<tr class='tr-table-product'>\n<td class='td-table-product'><strong>Linear Formula<\/strong><\/td>\n<td class='td-table-product'><span id='chem-formula'>C5H10Br2O2<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>CAS Number: 3296-90-0 MW (g\/mol): 261,94 Beilstein: n.a. CE Number: 221-967-7 MDL Number: MFCD00004688 ID PubChem: 18692 IUPAC Name 2,2-bis(bromomethyl)propane-1,3-diol Linear Formula C5H10Br2O2<\/p>\n","protected":false},"featured_media":89665,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[185],"product_tag":[],"class_list":["post-101759","product","type-product","status-publish","has-post-thumbnail","product_cat-analytical-standard-en","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product\/101759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media\/89665"}],"wp:attachment":[{"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/media?parent=101759"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_brand?post=101759"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_cat?post=101759"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.crmlabstandard.com\/en\/wp-json\/wp\/v2\/product_tag?post=101759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}